{"id":8749,"date":"2022-03-14T14:00:00","date_gmt":"2022-03-14T14:00:00","guid":{"rendered":"https:\/\/vivreauportugalconsulting.com\/?p=8749"},"modified":"2022-08-26T11:54:27","modified_gmt":"2022-08-26T10:54:27","slug":"contrat-de-travail-au-portugal-2","status":"publish","type":"post","link":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/contrat-de-travail-au-portugal-2\/","title":{"rendered":"Comment fonctionne la p\u00e9riode d&rsquo;essai d&rsquo;un contrat de travail au Portugal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Selon l&rsquo;article 111 du Code du travail au Portugal, la p\u00e9riode d&rsquo;essai correspond au temps initial d&rsquo;ex\u00e9cution du contrat de travail, pendant lequel les parties appr\u00e9cient l&rsquo;int\u00e9r\u00eat de sa poursuite.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment fonctionne la p\u00e9riode d&rsquo;essai d&rsquo;un contrat de travail au Portugal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ainsi, pendant cette p\u00e9riode, les parties (<a href=\"https:\/\/vivreauportugalconsulting.com\/creer-une-entreprise-au-portugal\/\" data-type=\"page\" data-id=\"5902\">employeurs et employ\u00e9s<\/a>) \u00e9valuent si elles sont int\u00e9ress\u00e9es ou non par la poursuite de la relation de travail. En d&rsquo;autres termes, c&rsquo;est le moment pour les parties d&rsquo;apprendre \u00e0 se conna\u00eetre et de d\u00e9cider s&rsquo;il est judicieux ou non de poursuivre le contrat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par exemple, un travailleur n&rsquo;aime pas son environnement de travail ou ne s&rsquo;identifie pas aux r\u00e8gles ou conditions impos\u00e9es par l&#8217;employeur. Ou, dans le cas de l&#8217;employeur, il pense que le travail n&rsquo;est pas bien fait par l&#8217;employ\u00e9 parce qu&rsquo;il n&rsquo;a pas les comp\u00e9tences qu&rsquo;il pensait avoir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La p\u00e9riode d&rsquo;essai peut \u00eatre r\u00e9duite, voire supprim\u00e9e, par accord \u00e9crit entre les parties. Cela signifie, au contraire, qu&rsquo;elle ne peut \u00eatre \u00e9tendue ou prolong\u00e9e. Elle peut \u00e9galement \u00eatre r\u00e9duite par un instrument de r\u00e9glementation collective du travail.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quant \u00e0 sa dur\u00e9e, si le contrat est conclu pour une dur\u00e9e ind\u00e9termin\u00e9e (sans \u00e9ch\u00e9ance), sa dur\u00e9e sera la suivante :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>90 jours pour la plupart des travailleurs ;<\/li><li>180 jours pour les travailleurs occupant des emplois techniquement complexes, \u00e0 haut degr\u00e9 de responsabilit\u00e9 ou exigeant une qualification particuli\u00e8re, occupant des postes de confiance ou \u00e0 la recherche d&rsquo;un premier emploi et qui sont des ch\u00f4meurs de longue dur\u00e9e ;<\/li><li>240 jours pour les travailleurs occupant des postes de direction et plus.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En revanche, s&rsquo;il est conclu pour une p\u00e9riode d\u00e9termin\u00e9e, il aura la dur\u00e9e suivante :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>30 jours dans le cas d&rsquo;un contrat de six mois ou plus ;<\/li><li>15 jours dans le cas d&rsquo;un contrat \u00e0 dur\u00e9e d\u00e9termin\u00e9e de moins de six mois ou d&rsquo;un contrat \u00e0 durer d\u00e9termin\u00e9e dont la dur\u00e9e pr\u00e9visible n&rsquo;exc\u00e8de pas cette limite.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cas des contrats de services command\u00e9s, l&rsquo;existence d&rsquo;une p\u00e9riode d&rsquo;essai d\u00e9pend d&rsquo;une stipulation expresse du contrat et ne peut d\u00e9passer 180 jours.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9compte de cette p\u00e9riode commence \u00e0 partir du moment o\u00f9 le travailleur commence \u00e0 ex\u00e9cuter son travail, y compris le temps pass\u00e9 en formation d\u00e9termin\u00e9 par l&#8217;employeur, pour autant qu&rsquo;il ne d\u00e9passe pas la moiti\u00e9 de la dur\u00e9e de cette p\u00e9riode.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En revanche, dans le calcul ci-dessus, les jours d&rsquo;absence (m\u00eame justifi\u00e9s), les cong\u00e9s, le licenciement ou la suspension du contrat ne sont pas compt\u00e9s. Enfin, si l&#8217;employeur ou l&#8217;employ\u00e9, pendant cette p\u00e9riode, d\u00e9cide qu&rsquo;il n&rsquo;est pas judicieux de maintenir le contrat de travail, ils peuvent y mettre fin, sans pr\u00e9avis ni invocation d&rsquo;un motif valable, et sans droit \u00e0 une indemnit\u00e9 ou \u00e0 une compensation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Font exception \u00e0 cette r\u00e8gle les cas o\u00f9, la p\u00e9riode ayant dur\u00e9 plus de 60 jours, la r\u00e9siliation du contrat par l&#8217;employeur d\u00e9pend d&rsquo;un pr\u00e9avis de sept jours. Ainsi que les cas dans lesquels, la p\u00e9riode ayant dur\u00e9 plus de 120 jours, l&#8217;employeur doit donner un pr\u00e9avis de 15 jours.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si, pour une raison quelconque, le pr\u00e9avis susmentionn\u00e9 n&rsquo;est pas respect\u00e9 en totalit\u00e9 ou en partie, l&#8217;employeur doit payer au salari\u00e9 les jours de pr\u00e9avis manquants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le <a href=\"https:\/\/dre.pt\/dre\/legislacao-consolidada\/lei\/2009-34546475\" target=\"_blank\" rel=\"noreferrer noopener\">pr\u00e9avis de r\u00e9siliation<\/a> n&rsquo;est soumis \u00e0 aucune forme, c&rsquo;est-\u00e0-dire qu&rsquo;il peut \u00eatre donn\u00e9 verbalement, et n&rsquo;est soumis \u00e0 aucune proc\u00e9dure pr\u00e9alable. Toutefois, afin d&rsquo;avoir une preuve de cette r\u00e9siliation du contrat, il est toujours pr\u00e9f\u00e9rable de le faire par \u00e9crit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon l&rsquo;article 111 du Code du travail au Portugal, la p\u00e9riode d&rsquo;essai correspond au temps initial d&rsquo;ex\u00e9cution du contrat de travail, pendant lequel les parties appr\u00e9cient l&rsquo;int\u00e9r\u00eat de sa poursuite.<\/p>\n","protected":false},"author":1,"featured_media":6363,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Vous \u00eates sur le point de signer un contrat de travail au Portugal et vous vous posez des questions sur la dur\u00e9e de la p\u00e9riode d'essai. \n\nCet article est fait pour vous. ","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1684,3308],"tags":[],"class_list":["post-8749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscalites-des-expatrier-au-portugal","category-economie-du-portugal"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vivreauportugalconsulting.com\/wp-content\/uploads\/2019\/09\/contrat-de-travail-au-portugal.jpg?fit=850%2C410&ssl=1","_links":{"self":[{"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/posts\/8749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=8749"}],"version-history":[{"count":0,"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/posts\/8749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/media\/6363"}],"wp:attachment":[{"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=8749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=8749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vivreauportugalconsulting.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=8749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}